{"id":2247,"count":0,"description":"","link":"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/","name":"Dr. Alex Shteynshlyuger Urologist ZocDoc","slug":"dr-alex-shteynshlyuger-urologist-zocdoc-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Alex Shteynshlyuger Urologist ZocDoc Archives - New York Urology Specialists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Alex Shteynshlyuger Urologist ZocDoc Archives - New York Urology Specialists\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/\" \/>\n<meta property=\"og:site_name\" content=\"New York Urology Specialists\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/\",\"url\":\"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/\",\"name\":\"Dr. Alex Shteynshlyuger Urologist ZocDoc Archives - New York Urology Specialists\",\"isPartOf\":{\"@id\":\"https:\/\/www.newyorkurologyspecialists.com\/es\/#website\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.newyorkurologyspecialists.com\/es\/#website\",\"url\":\"https:\/\/www.newyorkurologyspecialists.com\/es\/\",\"name\":\"New York Urology Specialists\",\"description\":\"Urology Care for Men and Women\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.newyorkurologyspecialists.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Alex Shteynshlyuger Urologist ZocDoc Archives - New York Urology Specialists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/","og_locale":"es_ES","og_type":"article","og_title":"Dr. Alex Shteynshlyuger Urologist ZocDoc Archives - New York Urology Specialists","og_url":"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/","og_site_name":"New York Urology Specialists","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/","url":"https:\/\/www.newyorkurologyspecialists.com\/es\/blog\/news\/tag\/dr-alex-shteynshlyuger-urologist-zocdoc-es\/","name":"Dr. Alex Shteynshlyuger Urologist ZocDoc Archives - New York Urology Specialists","isPartOf":{"@id":"https:\/\/www.newyorkurologyspecialists.com\/es\/#website"},"inLanguage":"es-ES"},{"@type":"WebSite","@id":"https:\/\/www.newyorkurologyspecialists.com\/es\/#website","url":"https:\/\/www.newyorkurologyspecialists.com\/es\/","name":"New York Urology Specialists","description":"Urology Care for Men and Women","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.newyorkurologyspecialists.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.newyorkurologyspecialists.com\/es\/wp-json\/wp\/v2\/tags\/2247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newyorkurologyspecialists.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.newyorkurologyspecialists.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.newyorkurologyspecialists.com\/es\/wp-json\/wp\/v2\/posts?tags=2247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}